{"id":15467,"date":"2023-12-28T17:13:53","date_gmt":"2023-12-28T20:13:53","guid":{"rendered":"https:\/\/com-automotive.com\/alternador-24v-175a-8sc3157v-j180-sin-polea\/"},"modified":"2023-12-28T17:13:53","modified_gmt":"2023-12-28T20:13:53","slug":"alternador-24v-175a-8sc3157v-j180-sin-polea","status":"publish","type":"product","link":"https:\/\/com-automotive.com\/es\/alternador-24v-175a-8sc3157v-j180-sin-polea\/","title":{"rendered":"Alternador 24V 175A 8SC3157V J180 sin polea<span class=\"product-sku\" style=\"display: block; font-size: 0.85em; color: #777; margin-top: 5px; margin-bottom: 5px;\">SKU: 8000.3157-COM<\/span>"},"content":{"rendered":"<h1><strong>COM-AUTOMOTIVE, calidad de dise\u00f1o original.<\/strong><\/h1>\n<h2>Preguntas m\u00e1s frecuentes<\/h2>\n<h3><strong>\u00bfCu\u00e1les son las referencias cruzadas?<\/strong><\/h3>\n<p>8SC3157V, 8SC3157V, 3001117,3001117, 3088320, 3629351, C3088320, C3629351, 5000898799, 8497489, 11.204.021, AAT3312, IA1433., DRA0267, 0267, 8EL730137-001, 8EL730137001, 859477B, 859477PB, 8SC3009ZA, 8SC3157V.<\/p>\n<h2><strong>Tabla de aplicaci\u00f3n<\/strong><\/h2>\n<p>Volvo Penta TAMD120 TAMD100 TAMD 162 Cummins y Caterpillar Cargador Contanier Linde Cummins . ORIGINALES : Leece Neville 8SC3157V \/ Prestolite 8SC3157V \/ 8SC3157<\/p>\n<div><\/div>\n<div>ATENCI\u00d3N:<\/div>\n<div>Recomendamos que la instalaci\u00f3n de 0001192105 la realice un profesional formado y especializado.<\/div>\n<div>S\u00f3lo adquiera este producto en 0001192105 si est\u00e1 seguro de que es compatible con su veh\u00edculo. Si tiene alguna duda, no dude en ponerse en contacto con nosotros. Nuestro horario de apertura es de lunes a viernes de 8 a 18 h.<\/div>\n<div><\/div>\n<div>Sobre nosotros<\/div>\n<div>COM Automotive est\u00e1 especializada en piezas de autom\u00f3vil de dise\u00f1o original para el sector de la reparaci\u00f3n posventa, clientes industriales y fabricantes de veh\u00edculos especiales OEM.<\/div>\n<div>Nuestro equipo tiene m\u00e1s de 28 a\u00f1os de experiencia en la fabricaci\u00f3n y el suministro de piezas de automoci\u00f3n a escala mundial.<\/div>\n<div>Nuestra MISI\u00d3N es ofrecer productos de dise\u00f1o original con una calidad impecable y una sustituci\u00f3n personalizada.<\/div>\n<div>Nuestra VISI\u00d3N es promover el crecimiento y un valor inigualable para nuestros clientes.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>8SC3157V-COM. En stock. Ref: 8SC3157V, 8SC3157V, 3001117, 3088320, 3629351, C3088320, C3629351, 5000898799, 8497489, 11.204.021, AAT3312, IA1433., DRA0267, 0267, 8EL730137-001, 8EL730137001, 859477B, 859477PB, 8SC3009ZA, 8SC3157V. &#8211; compatible con: Caterpillar. Marca: COM Automotive &#8211; Producto con calidad y dise\u00f1o originales. Compatible con Prestolite<\/p>\n","protected":false},"featured_media":20488,"comment_status":"open","ping_status":"closed","template":"","meta":{"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[8109],"product_tag":[11203,11195,11186,11187,11188,11191,11193,11209,11211,11205,11207,11214,11184,11197,11189,11190,11201,11199],"class_list":["post-15467","product","type-product","status-publish","has-post-thumbnail","product_cat-alternador-es-2","product_tag-0267-es","product_tag-11-204-021-es","product_tag-3001117-es","product_tag-3088320-es","product_tag-3629351-es","product_tag-5000898799-es","product_tag-8497489-es","product_tag-859477b-es","product_tag-859477pb-es","product_tag-8el730137-001-es","product_tag-8el730137001-es","product_tag-8sc3009za-es","product_tag-8sc3157v-es","product_tag-aat3312-es","product_tag-c3088320-es","product_tag-c3629351-es","product_tag-dra0267-es","product_tag-ia1433-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/product\/15467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/comments?post=15467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/media\/20488"}],"wp:attachment":[{"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/media?parent=15467"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/product_brand?post=15467"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/product_cat?post=15467"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/com-automotive.com\/es\/wp-json\/wp\/v2\/product_tag?post=15467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}